{"id":93669,"date":"2026-09-01T17:52:04","date_gmt":"2026-09-01T15:52:04","guid":{"rendered":"https:\/\/www.mycampermarket.com\/?post_type=annonces&#038;p=93669"},"modified":"2026-09-01T17:52:04","modified_gmt":"2026-09-01T15:52:04","slug":"van-amenage-e-jympy-iii-citroen-93669","status":"publish","type":"annonces","link":"https:\/\/www.mycampermarket.com\/it\/annonces\/van-amenage-e-jympy-iii-citroen-93669\/","title":{"rendered":"Van am\u00e9nag\u00e9 \u00eb-Jympy III Citro\u00ebn"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2316,"featured_media":93677,"template":"","meta":{"_seopress_titles_title":"Citro\u00ebn \u00eb-Jumpy III van am\u00e9nag\u00e9 6 places \u2013 2021 \u2013 30 000 \u20ac","_seopress_titles_desc":"Citro\u00ebn \u00eb-Jumpy III 2021, 136 ch, 83 500 km, 6 places, am\u00e9nag\u00e9 van 2\/3 pers. D\u00e9montable sans outils. 30 000 \u20ac.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"dmedia_modele":"\u00eb-Jympy III","dmedia_modele_marque":"","dmedia_genre":"Occasion","dmedia_prix":"30000","dmedia_dev":"EUR","dmedia_kilometrage":83500,"dmedia_cylindree":0,"type_de_carburant":"Electrique","dmedia_boite-de-vitesses":"Automatique","dmedia_motricite":"Traction avant","dmedia_puissance":"136","dmedia_imatriculation":"1624233600","dmedia_annee":2021,"dmedia_expertise":"1768521600","dmedia_longueur":5309,"dmedia_largeur":1920,"dmedia_hauteur":1935,"dmedia_poid_vide":2188,"dmedia_poid_total":3100,"dmedia_n_place":6,"dmedia_n_couch":4,"dmedia_npa_ville":"83170 Rougiers","dmedia_premium":7,"dmedia_site_ext":"","dmedia_video":"","dmedia_infos":"","dmedia_interlocuteur":"","dmedia_tel_contact":"","dmedia_internet":"","dmedia_dte_top":"1788889924","dmedia_dte_top_start":"1788285124","dmedia_dte_top_end":"1788889924","dmedia_dte_delete":"","dmedia_info_delete":"","dmedia_meta_des":"","dmedia_dte_pay":"","dmedia_dte_rap":"","dmedia_etape":8,"dmedia_lgs":"fr","dmedia_annonce_info_lgs":"","dmedia_annonce_info_fr":"Van 3-en-1 full \u00e9lectrique, 6 places assises en mode route (inscrits carte grise), banquette arri\u00e8re relevable lib\u00e9rant un espace de vie am\u00e9nag\u00e9 pour 2 adultes + 1 ou 2 enfants. Les am\u00e9nagements sont d\u00e9montables sans outils en quelques minutes puis manu-portables, pour retrouver le plein volume de 6m3 du format utilitaire. V\u00e9hicule silencieux, avec tr\u00e8s peu d'entretien, et de plus en plus \u00e9conomique au kilom\u00e8tre...\nPrix de vente TTC (TVA non r\u00e9cup\u00e9rable). Le prix a \u00e9t\u00e9 fix\u00e9 apr\u00e8s une longue \u00e9tude des prix du march\u00e9, il n'est n\u00e9gociable qu'en d\u00e9montrant que ce prix est au dessus du march\u00e9, en apportant des preuves de v\u00e9hicules comparables vendus moins chers.\nAm\u00e9nagements : \n    banquette avec coffres transformable en lit 190x120cm\n    couchette enfant relevable 135x50cm avec filet de s\u00e9curit\u00e9 (une deuxi\u00e8me couchette sym\u00e9trique sur le c\u00f4t\u00e9 oppos\u00e9 peut \u00eatre construite, \u00e0 n\u00e9gocier)\n    meuble cuisine avec \u00e9vier et pompe \u00e0 main (Whale marine)\n    r\u00e9servoirs 20l eau potable et 20l eaux us\u00e9es\n    plaque cuisson induction (1800W)\n    frigo compression 11 litres (format glaci\u00e8re donc mobile)\n    grande table repliable (sans pieds pour faciliter la circulation autour)\n    3 rangements dans les portes arri\u00e8res\n    toilette s\u00e8che\n    lanterneau Thule Omnivent (100cm2 a\u00e9ration permanente) + ventilation basse 50cm2\n    isolation Armaflex 20 mm toit et 10 mm parois lat\u00e9rales, li\u00e8ge 4mm sous plancher CP 10mm\n    meubles et habillages de parois en CP peuplier 5, 10 ou 15 mm, 3 couches huile dure qualit\u00e9 \"plan de travail\"\n\nEnergie : \n    batterie accessoire 12V LiFePo4 4014 Wh \/ 314 Ah (WattCycle Mini Super plus avec BT, homologu\u00e9e ECE R10, neuve)\n    chargeur Victron Blue Smart IP22 230VAC-12VDC 30A (avec BT, homologu\u00e9 ECE R10)\n    chargeur-booster Victron 12VDC-12VDC Orion TR Smart (avec BT, homologu\u00e9 ECE R10)\n    convertisseur-onduleur 12VDC-230VAC CreaBest 3000W (homologu\u00e9 ECE R10)\n    c\u00e2bles 12V vers le convertisseur-onduleur en 70mm2, vers les chargeurs en 16mm2, cosses serties avec pince \u00e0 sertir pro, coupes circuits et fusibles adapt\u00e9s aux c\u00e2bles (300A et 60 A pour les principaux)\n    2 lampes LED orientables avec chargeurs USB-A int\u00e9gr\u00e9s\n    thermom\u00e8tres int\/ext\n    voltm\u00e8tres batteries 12V accessoire et porteur\n    chargeur USB-A &amp; USB-C\n    la batterie accessoire ultra haute capacit\u00e9 de 4 kWh offre une autonomie de 4-10 jours sans recharges (moiti\u00e9 moins l'hiver avec petit chauffage mobile soufflant 350W 4h par jour), et cette batterie se recharge en roulant, durant la charge du porteur, ou tout simplement en allumant le contact pour puiser dans la r\u00e9serve encore plus grande des 75 kWh du porteur... ceci rend les panneaux solaires superflus et permet de garer le v\u00e9hicule \u00e0 l'ombre.\n\nPorteur : \n    V\u00e9hicule 100% \u00e9lectrique Citro\u00ebn \u00eb-Jumpy 75 kWh (SoH 88.8% aucun changement depuis un an, batterie garantie 8 ans 24\/06\/29 ou 160000km)\n    moteur de traction \u00e9lectrique 136 ch avec 83500 km (\u00e9volutifs)\n    ch\u00e2ssis long (XL)\n    Barre d'attelage &amp; attache remorque\n    hauteur moins de 2 m\u00e8tres (permet de passer sous les barres \u00e0 2m des aires de repos et la plupart des parkings souterrains)\n    excellent \u00e9tat m\u00e9canique\/\u00e9lectrique\/carrosserie\n    4 pneus neufs\n    autonomie r\u00e9elle de 280km cet hiver, jusqu'\u00e0 294km cet \u00e9t\u00e9\n    recharge compl\u00e8te en une nuit sur wall box domestique 7kW, et recharges rapides 100kW offrant des d\u00e9bits de charge r\u00e9els d\u00e9passant les 400km\/h dans la plage 20-80%\n    exemple de trajet r\u00e9el : Marseille-Toulouse (400km) avec deux pauses de recharge de 30 min\n    Equipements : radio FM, connexion t\u00e9l Bluetooth avec kit mains libres, prise USB audio auxiliaire, condamnation centralis\u00e9e avec un plip plus une clef de secours, Limiteur de vitesse, R\u00e9gulateur de vitesse, Radar de recul, Cam\u00e9ra de recul, Frein \u00e0 main \u00e9lectrique, Aide au d\u00e9marrage en pente, Antiblocage des roues (ABS), R\u00e9partiteur \u00e9lectronique de freinage (REF), Assistance au freinage d'urgence (AFU), Antipatinage des roues (ASR), Contr\u00f4le dynamique de stabilit\u00e9 (CDS), Contr\u00f4le de traction intelligent, Contr\u00f4le de stabilit\u00e9 de la remorque (TSM), R\u00e9troviseurs ext\u00e9rieurs \u00e9lectriques et d\u00e9givrants, Vitres arri\u00e8res sur-teint\u00e9es, Climatisation manuelle, Si\u00e8ge conducteur r\u00e9glable en hauteur avec accoudoir, c\u00e2ble de recharge prise 230V domestique, c\u00e2ble prise Type 2 pour wallbox\/bornes, Chargeur embarqu\u00e9 7,4 kW\n    Contr\u00f4le technique de janvier 2026 pass\u00e9 sans contre visite, sera repass\u00e9 pour la vente\n\nLe v\u00e9hicule est actuellement en vente en cat\u00e9gorie CTTE (utilitaire) sur le carte grise, ce qui requiert pour rouler de remonter la grille articul\u00e9e dite \"arr\u00eat de charge\" qui se rel\u00e8ve avec la banquette arri\u00e8re relevable (la grille est dispo mais retir\u00e9e sur les photos). Le dossier d'homologation VASP est en pr\u00e9paration (3-4 mois de d\u00e9lais pr\u00e9visible), apr\u00e8s quoi la grille d'arr\u00eat de charge ne sera plus requise en roulant. Le prix de vente sera r\u00e9vis\u00e9 \u00e0 la hausse apr\u00e8s homologation VASP (+1500\u20ac).","dmedia_annonce_info_ia":"","dmedia_galimage_public":"93677,93685,93681,93682,93684,93680,93683,93692,93678,93686,93687,93688,93689,93679,93690,93691","dmedia_galimage":"93677,93685,93681,93682,93684,93680,93683,93692,93678,93686,93687,93688,93689,93679,93690,93691","dmedia_opt_visibilite":2,"dmedia_opt_expo":2,"dmedia_opt_speed":2,"dmedia_opt_social":2},"type-de-vehicule":[8],"localisation":[219,37],"constructeur":[],"marque":[54],"equipement-cellule":[26,27,32],"equipement-vehicule":[15,19,20,18,47,46,48,49,50,21],"type-de-lit":[1013,1015],"type-annonces":[],"class_list":["post-93669","annonces","type-annonces","status-publish","has-post-thumbnail","hentry","type-de-vehicule-van","localisation-83-var","localisation-france","marque-citroen","equipement-cellule-cuisiniere-electrique","equipement-cellule-frigo","equipement-cellule-wc-compost","equipement-vehicule-abs","equipement-vehicule-airbag-cote-conducteur","equipement-vehicule-airbag-cote-passager","equipement-vehicule-attelage","equipement-vehicule-camera-de-recul","equipement-vehicule-climatisation","equipement-vehicule-direction-assistee","equipement-vehicule-leve-vitre-electrique","equipement-vehicule-regulateur-de-vitesse","equipement-vehicule-verrouillage-central","type-de-lit-lit-escamotable","type-de-lit-lits-superposes"],"_links":{"self":[{"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/annonces\/93669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/annonces"}],"about":[{"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/types\/annonces"}],"author":[{"embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/users\/2316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/media\/93677"}],"wp:attachment":[{"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/media?parent=93669"}],"wp:term":[{"taxonomy":"type-de-vehicule","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/type-de-vehicule?post=93669"},{"taxonomy":"localisation","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/localisation?post=93669"},{"taxonomy":"constructeur","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/constructeur?post=93669"},{"taxonomy":"marque","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/marque?post=93669"},{"taxonomy":"equipement-cellule","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/equipement-cellule?post=93669"},{"taxonomy":"equipement-vehicule","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/equipement-vehicule?post=93669"},{"taxonomy":"type-de-lit","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/type-de-lit?post=93669"},{"taxonomy":"type-annonces","embeddable":true,"href":"https:\/\/www.mycampermarket.com\/it\/wp-json\/wp\/v2\/type-annonces?post=93669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}